{"id":36972,"date":"2024-11-19T13:04:30","date_gmt":"2024-11-19T19:04:30","guid":{"rendered":"https:\/\/tonala.gob.mx\/portal\/?p=36972"},"modified":"2024-11-21T08:58:31","modified_gmt":"2024-11-21T14:58:31","slug":"resultados-de-la-consulta-publica-del-plan-de-desarrollo-urbano-de-centro-de-poblacion","status":"publish","type":"post","link":"https:\/\/tonala.gob.mx\/portal\/2024\/11\/19\/resultados-de-la-consulta-publica-del-plan-de-desarrollo-urbano-de-centro-de-poblacion\/","title":{"rendered":"Resultados de la Consulta P\u00fablica del Plan de Desarrollo Urbano de Centro de Poblaci\u00f3n"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El Gobierno de Tonal\u00e1, a trav\u00e9s de la Direcci\u00f3n General de Planeaci\u00f3n y Desarrollo Urbano Sustentable agradece su valiosa participaci\u00f3n en el proceso de Consulta P\u00fablica del Plan de Desarrollo Urbano de Centro de Poblaci\u00f3n (PDUCP) del Municipio de Tonal\u00e1, Jalisco, que se llev\u00f3 a cabo a partir del 1. \u00b0 de agosto, finalizando el d\u00eda 31 de agosto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Sus opiniones y aportaciones son fundamentales para una mejor planeaci\u00f3n urbana de nuestro Municipio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Las observaciones recibidas durante el periodo de consulta fueron atendidas, y quedan sujetas a lo establecido en los art\u00edculos 11, fracci\u00f3n III; art\u00edculo 82, fracci\u00f3n II; art\u00edculo 83, art\u00edculo 98 fracciones III, IV, V, VI, VII Y VIII, art\u00edculo 99 del C\u00f3digo Urbano para el Estado de Jalisco, las\u00a0respuestas<strong> a las mismas ya se encuentran disponibles en Pino Suarez #32, Col. Centro, Tonal\u00e1 Jalisco.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br><strong>\u00a1Gracias por ser parte de la Planeaci\u00f3n Urbana de nuestro Municipio!<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Gobierno de Tonal\u00e1, a trav\u00e9s de la Direcci\u00f3n General de Planeaci\u00f3n y Desarrollo Urbano Sustentable agradece su valiosa participaci\u00f3n<\/p>\n","protected":false},"author":2,"featured_media":35829,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[2],"tags":[],"class_list":["post-36972","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunicacion-social"],"_links":{"self":[{"href":"https:\/\/tonala.gob.mx\/portal\/wp-json\/wp\/v2\/posts\/36972","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tonala.gob.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tonala.gob.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tonala.gob.mx\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tonala.gob.mx\/portal\/wp-json\/wp\/v2\/comments?post=36972"}],"version-history":[{"count":3,"href":"https:\/\/tonala.gob.mx\/portal\/wp-json\/wp\/v2\/posts\/36972\/revisions"}],"predecessor-version":[{"id":36992,"href":"https:\/\/tonala.gob.mx\/portal\/wp-json\/wp\/v2\/posts\/36972\/revisions\/36992"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tonala.gob.mx\/portal\/wp-json\/wp\/v2\/media\/35829"}],"wp:attachment":[{"href":"https:\/\/tonala.gob.mx\/portal\/wp-json\/wp\/v2\/media?parent=36972"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tonala.gob.mx\/portal\/wp-json\/wp\/v2\/categories?post=36972"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tonala.gob.mx\/portal\/wp-json\/wp\/v2\/tags?post=36972"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}