{"id":31511,"date":"2020-09-01T16:53:19","date_gmt":"2020-09-01T22:53:19","guid":{"rendered":"https:\/\/tonala.gob.mx\/portal\/?p=31511"},"modified":"2020-09-02T08:55:52","modified_gmt":"2020-09-02T14:55:52","slug":"gobierno-de-tonala-realiza-inversion-de-mas-de-2-mdp-en-calles-y-servicios-en-san-gaspar","status":"publish","type":"post","link":"https:\/\/tonala.gob.mx\/portal\/2020\/09\/01\/gobierno-de-tonala-realiza-inversion-de-mas-de-2-mdp-en-calles-y-servicios-en-san-gaspar\/","title":{"rendered":"Gobierno de Tonal\u00e1 realiza inversi\u00f3n de m\u00e1s de 2 MDP en calles y servicios en San Gaspar"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/tonala.gob.mx\/portal\/wp-content\/uploads\/2020\/09\/WhatsApp-Image-2020-09-01-at-3.58.01-PM-1-1024x682.jpeg\" alt=\"\" class=\"wp-image-31512\" srcset=\"https:\/\/tonala.gob.mx\/portal\/wp-content\/uploads\/2020\/09\/WhatsApp-Image-2020-09-01-at-3.58.01-PM-1-1024x682.jpeg 1024w, https:\/\/tonala.gob.mx\/portal\/wp-content\/uploads\/2020\/09\/WhatsApp-Image-2020-09-01-at-3.58.01-PM-1-300x200.jpeg 300w, https:\/\/tonala.gob.mx\/portal\/wp-content\/uploads\/2020\/09\/WhatsApp-Image-2020-09-01-at-3.58.01-PM-1-768x512.jpeg 768w, https:\/\/tonala.gob.mx\/portal\/wp-content\/uploads\/2020\/09\/WhatsApp-Image-2020-09-01-at-3.58.01-PM-1.jpeg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Esta ma\u00f1ana, el presidente municipal, Juan Antonio Gonz\u00e1lez Mora, realiz\u00f3 un recorrido para supervisar las obras de empedrado zampeado y sustituci\u00f3n de red de drenaje sanitario que se realizan en calles de la delegaci\u00f3n de San Gaspar, estos trabajos de infraestructura hidrosanitaria y renovaci\u00f3n de pisos beneficiar\u00e1n a decenas de familias tonaltecas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;Con una inversi\u00f3n de m\u00e1s de 2 millones de pesos, durante el recorrido de supervisi\u00f3n el presidente municipal, Juan Antonio Gonz\u00e1lez, resalt\u00f3 que estos trabajos de infraestructura b\u00e1sica se realizan despu\u00e9s de m\u00e1s de 12 a\u00f1os en que no se interven\u00eda en estas calles, ya que las y los vecinos ped\u00edan se atendiera sus problemas de drenaje sanitario.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/tonala.gob.mx\/portal\/wp-content\/uploads\/2020\/09\/WhatsApp-Image-2020-09-01-at-3.58.00-PM-2-1024x682.jpeg\" alt=\"\" class=\"wp-image-31513\" srcset=\"https:\/\/tonala.gob.mx\/portal\/wp-content\/uploads\/2020\/09\/WhatsApp-Image-2020-09-01-at-3.58.00-PM-2-1024x682.jpeg 1024w, https:\/\/tonala.gob.mx\/portal\/wp-content\/uploads\/2020\/09\/WhatsApp-Image-2020-09-01-at-3.58.00-PM-2-300x200.jpeg 300w, https:\/\/tonala.gob.mx\/portal\/wp-content\/uploads\/2020\/09\/WhatsApp-Image-2020-09-01-at-3.58.00-PM-2-768x512.jpeg 768w, https:\/\/tonala.gob.mx\/portal\/wp-content\/uploads\/2020\/09\/WhatsApp-Image-2020-09-01-at-3.58.00-PM-2.jpeg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;\u201cNos encontramos en la calle Zaragoza, en una obra que ya era muy necesaria donde se est\u00e1 introduciendo tuber\u00eda para drenaje sanitario, son m\u00e1s de 1,200 metros cuadrados de empedrado zampeado, muy necesarios porque son m\u00e1s de 12 a\u00f1os en que no se pon\u00eda atenci\u00f3n en estas calles tan necesitadas; aqu\u00ed en San Gaspar se ve la injusticia de a\u00f1os de lo que fue abandonar el Oriente del \u00c1rea Metropolitana\u201d, resalt\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;Los trabajos que se realizan son la sustituci\u00f3n de drenaje sanitario en la calle Nicol\u00e1s Bravo y Zaragoza, as\u00ed como la instalaci\u00f3n de empedrado zampeado, se trata de la instalaci\u00f3n de 338 ml de tuber\u00eda PVC sanitario de 12\u201d de di\u00e1metro para 67 descargas sanitarias.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esta ma\u00f1ana, el presidente municipal, Juan Antonio Gonz\u00e1lez Mora, realiz\u00f3 un recorrido para supervisar las obras de empedrado zampeado y<\/p>\n","protected":false},"author":2,"featured_media":31514,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[2],"tags":[],"class_list":["post-31511","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunicacion-social"],"_links":{"self":[{"href":"https:\/\/tonala.gob.mx\/portal\/wp-json\/wp\/v2\/posts\/31511","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tonala.gob.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tonala.gob.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tonala.gob.mx\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tonala.gob.mx\/portal\/wp-json\/wp\/v2\/comments?post=31511"}],"version-history":[{"count":1,"href":"https:\/\/tonala.gob.mx\/portal\/wp-json\/wp\/v2\/posts\/31511\/revisions"}],"predecessor-version":[{"id":31515,"href":"https:\/\/tonala.gob.mx\/portal\/wp-json\/wp\/v2\/posts\/31511\/revisions\/31515"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tonala.gob.mx\/portal\/wp-json\/wp\/v2\/media\/31514"}],"wp:attachment":[{"href":"https:\/\/tonala.gob.mx\/portal\/wp-json\/wp\/v2\/media?parent=31511"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tonala.gob.mx\/portal\/wp-json\/wp\/v2\/categories?post=31511"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tonala.gob.mx\/portal\/wp-json\/wp\/v2\/tags?post=31511"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}