{"id":28,"date":"2015-10-23T12:00:18","date_gmt":"2015-10-23T12:00:18","guid":{"rendered":"http:\/\/tonala.gob.mx\/wpaco\/?p=28"},"modified":"2015-11-20T15:50:55","modified_gmt":"2015-11-20T15:50:55","slug":"preparado-el-gobierno-municipal-de-tonala-ante-el-huracan-patricia","status":"publish","type":"post","link":"https:\/\/tonala.gob.mx\/portal\/2015\/10\/23\/preparado-el-gobierno-municipal-de-tonala-ante-el-huracan-patricia\/","title":{"rendered":"Preparado el Gobierno Municipal de Tonal\u00e1 ante el Hurac\u00e1n \u201cPatricia\u201d"},"content":{"rendered":"<p>Tonal\u00e1, Jalisco. 23 de Octubre de 2015<\/p>\n<p>Bolet\u00edn No. 008<\/p>\n<p id=\"u2187-10\">\u2022 Se realizan labores de desazolve.<\/p>\n<p>\u2022 Comisar\u00eda de Seguridad P\u00fablica, Protecci\u00f3n Civil y Bomberos,\u00a0 Servicios M\u00e9dicos Municipales en alerta ante cualquier contingencia.<\/p>\n<p><a href=\"https:\/\/tonala.gob.mx\/portal\/wp-content\/uploads\/2015\/10\/1.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-29\" src=\"https:\/\/tonala.gob.mx\/portal\/wp-content\/uploads\/2015\/10\/1.jpg\" alt=\"1\" width=\"1000\" height=\"500\" srcset=\"https:\/\/tonala.gob.mx\/portal\/wp-content\/uploads\/2015\/10\/1.jpg 1000w, https:\/\/tonala.gob.mx\/portal\/wp-content\/uploads\/2015\/10\/1-300x150.jpg 300w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/a><\/p>\n<p>Desde ayer jueves por la noche, el Consejo Municipal de Protecci\u00f3n Civil y el Comit\u00e9 de Emergencias del municipio de Tonal\u00e1, encabezados ambos por el presidente municipal Sergio Ch\u00e1vez D\u00e1valos, est\u00e1n en alerta y monitoreo constante de lo que acontece con el Hurac\u00e1n \u201cPatricia\u201d y prevenir las consecuencias que las tormentas producto del meteoro, pudiesen provocar en las \u00e1reas susceptibles de inundarse en la cuna alfarera.<\/p>\n<p>Esta ma\u00f1ana, Ch\u00e1vez D\u00e1valos supervis\u00f3 los trabajos emergentes de desazolve que la Unidad de Protecci\u00f3n Civil y Bomberos efect\u00faa en el canal de aguas negras que corre desde Tlaquepaque y cruza la colonia Santa Paula, Santa Isabel y El Dorado hasta su punto final en la Cuenca del Ahogado, e hizo otro tanto con la labor realizada en los afluentes que cruzan la colonia Arboledas de Tonal\u00e1.<\/p>\n<p>En el municipio existen alrededor de 14 zonas susceptibles de inundarse, como Santa Paula, Jauja, colonia 20 de noviembre, San Miguel la Punta, parte de la colonia Jalisco y en cabecera municipal las calles Alberca y Ju\u00e1rez, entre otros puntos en las que ya se tomaron las previsiones correspondientes pata evitar percances.<\/p>\n<p>Por otro lado, el presidente municipal gir\u00f3 instrucciones para habilitar refugios temporales en las colonias Santa Isabel, Puente Grande, Santa Paula, Jauja, Colonia Jalisco y Loma Dorada y en cabecera municipal en el Centro de Atenci\u00f3n Integral al Adulto Mayor (CAIAM) y en el Centro de Rehabilitaci\u00f3n Integral (CRI), \u00e9stos dos \u00faltimos ya est\u00e1n habilitados desde las 11:00 horas de este d\u00eda.<\/p>\n<p>As\u00ed mismo, el Presidente Municipal orden\u00f3 a los titulares de la Comisar\u00eda de Seguridad P\u00fablica, de Protecci\u00f3n Civil y Bomberos, y Servicios M\u00e9dicos Municipales permanecer encuartelados, en tanto no disminuya el riesgo que representa las fuertes lluvias que se espera se precipiten entre hoy, ma\u00f1ana y la madrugada del domingo\u00a0 a causa del fen\u00f3meno meteorol\u00f3gico<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tonal\u00e1, Jalisco. 23 de Octubre de 2015 Bolet\u00edn No. 008 \u2022 Se realizan labores de desazolve. \u2022 Comisar\u00eda de Seguridad<\/p>\n","protected":false},"author":2,"featured_media":73,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[2],"tags":[],"class_list":["post-28","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunicacion-social"],"_links":{"self":[{"href":"https:\/\/tonala.gob.mx\/portal\/wp-json\/wp\/v2\/posts\/28","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tonala.gob.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tonala.gob.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tonala.gob.mx\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tonala.gob.mx\/portal\/wp-json\/wp\/v2\/comments?post=28"}],"version-history":[{"count":2,"href":"https:\/\/tonala.gob.mx\/portal\/wp-json\/wp\/v2\/posts\/28\/revisions"}],"predecessor-version":[{"id":74,"href":"https:\/\/tonala.gob.mx\/portal\/wp-json\/wp\/v2\/posts\/28\/revisions\/74"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tonala.gob.mx\/portal\/wp-json\/wp\/v2\/media\/73"}],"wp:attachment":[{"href":"https:\/\/tonala.gob.mx\/portal\/wp-json\/wp\/v2\/media?parent=28"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tonala.gob.mx\/portal\/wp-json\/wp\/v2\/categories?post=28"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tonala.gob.mx\/portal\/wp-json\/wp\/v2\/tags?post=28"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}