{"id":195,"date":"2015-10-27T09:00:12","date_gmt":"2015-10-27T09:00:12","guid":{"rendered":"http:\/\/tonala.gob.mx\/portal\/?p=195"},"modified":"2015-11-20T15:51:05","modified_gmt":"2015-11-20T15:51:05","slug":"inauguran-la-primera-feria-municipal-de-empleo-tonala","status":"publish","type":"post","link":"https:\/\/tonala.gob.mx\/portal\/2015\/10\/27\/inauguran-la-primera-feria-municipal-de-empleo-tonala\/","title":{"rendered":"Inauguran la Primera Feria Municipal de Empleo Tonal\u00e1"},"content":{"rendered":"<p>Tonal\u00e1, Jalisco. 27 de Octubre de 2015<\/p>\n<p>Bolet\u00edn No. 010<\/p>\n<ul>\n<li>63 empresas con m\u00e1s de mil 800 vacantes<\/li>\n<\/ul>\n<p><a href=\"https:\/\/tonala.gob.mx\/portal\/wp-content\/uploads\/2015\/10\/Sin-t\u00edtulo-71.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-196\" src=\"https:\/\/tonala.gob.mx\/portal\/wp-content\/uploads\/2015\/10\/Sin-t\u00edtulo-71.jpg\" alt=\"Sin t\u00edtulo-7\" width=\"800\" height=\"445\" srcset=\"https:\/\/tonala.gob.mx\/portal\/wp-content\/uploads\/2015\/10\/Sin-t\u00edtulo-71.jpg 800w, https:\/\/tonala.gob.mx\/portal\/wp-content\/uploads\/2015\/10\/Sin-t\u00edtulo-71-300x167.jpg 300w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p>Con el objetivo de facilitar al ciudadano la b\u00fasqueda de nuevas oportunidades para mejorar su calidad de vida, mediante el acercamiento de diversos \u00a0espacios laborales en la iniciativa \u00a0privada, se realiz\u00f3 la primera Feria Municipal de Empleo Tonal\u00e1, que organiza el Gobierno Municipal a trav\u00e9s de la Direcci\u00f3n General de Promoci\u00f3n y Desarrollo Econ\u00f3mico, Tur\u00edstico y Artesanal.<\/p>\n<p>Durante el evento de inauguraci\u00f3n se cont\u00f3 con la presencia de representantes de 63 empresas que ofertaron m\u00e1s de mil 800 vacantes para diferentes perfiles, entre los que destacan, de intendencia, producci\u00f3n,\u00a0 auxiliar general, almacenista,\u00a0\u00a0 t\u00e9cnico electricista,\u00a0\u00a0 chofer,\u00a0 cobrador, vendedor,\u00a0 psic\u00f3logo, abogado,\u00a0 trabajador\u00a0 social,\u00a0 maestro\u00a0 tecn\u00f3logo, custodio,\u00a0\u00a0 docentes\u00a0 de Matem\u00e1ticas, Ingles, Derecho, entre otros.<\/p>\n<p>En representaci\u00f3n del presidente municipal de Tonal\u00e1, Sergio Ch\u00e1vez D\u00e1valos, asisti\u00f3 la regidora Ana Priscila Gonz\u00e1lez Garc\u00eda, presidenta de la Comisi\u00f3n Edilicia de Fomento y Desarrollo Econ\u00f3mico, quien destac\u00f3 que hoy en d\u00eda se vive un mundo m\u00e1s competitivo que exige una mayor preparaci\u00f3n y seguir adelante a pesar de las adversidades.<\/p>\n<p>Al respecto, se\u00f1al\u00f3: \u201cpor ello quiero aprovechar para hacer un reconocimiento a las mujeres, a los hombres y a los j\u00f3venes que est\u00e1n el d\u00eda de hoy aqu\u00ed acompa\u00f1\u00e1ndonos; es la clara prueba de quieren salir adelante, reitero la disposici\u00f3n que tendremos desde la comisi\u00f3n edilicia de fomento y desarrollo econ\u00f3mico que presido, para apoyar a todas aquellas actividades, programas y proyectos que fortalezcan la econom\u00eda de las familias tonaltecas\u201d.<\/p>\n<p>En el acto inaugural de corte de list\u00f3n, estuvieron tambi\u00e9n, el secretario general del Ayuntamiento, Enrique Guzm\u00e1n Loza, el director general de Promoci\u00f3n y Desarrollo Econ\u00f3mico, Tur\u00edstico y Artesanal, Miguel \u00c1ngel Wong \u00c1lvarez, el director del Instituto Municipal de la Juventud, Luis Alberto Celis Espinoza, la directora del\u00a0 Instituto Municipal de la Mujer, Martha Rosal\u00eda G\u00f3mez Ahumada.<\/p>\n<p>Cabe mencionar que entre las empresas que estar\u00e1n ofertando sus vacantes se encuentran: ETN,\u00a0 SEPRIOC,\u00a0 DAMSA, KELLY, CONSUBANCO, WORKEN, VPS SEGURIDAD, TUR, TIENDAS EXTRA, MULTIGAS, GRUPO SANDY, RAGAZZA FASHION, PROMOCONCEPTOS, PABS, OXXO, MAXIMUS PUBLICIDAD, MANPOWER, MUEBLES LACANDONA, entre otras.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tonal\u00e1, Jalisco. 27 de Octubre de 2015 Bolet\u00edn No. 010 63 empresas con m\u00e1s de mil 800 vacantes Con el<\/p>\n","protected":false},"author":2,"featured_media":196,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[2],"tags":[],"class_list":["post-195","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunicacion-social"],"_links":{"self":[{"href":"https:\/\/tonala.gob.mx\/portal\/wp-json\/wp\/v2\/posts\/195","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tonala.gob.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tonala.gob.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tonala.gob.mx\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tonala.gob.mx\/portal\/wp-json\/wp\/v2\/comments?post=195"}],"version-history":[{"count":1,"href":"https:\/\/tonala.gob.mx\/portal\/wp-json\/wp\/v2\/posts\/195\/revisions"}],"predecessor-version":[{"id":197,"href":"https:\/\/tonala.gob.mx\/portal\/wp-json\/wp\/v2\/posts\/195\/revisions\/197"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tonala.gob.mx\/portal\/wp-json\/wp\/v2\/media\/196"}],"wp:attachment":[{"href":"https:\/\/tonala.gob.mx\/portal\/wp-json\/wp\/v2\/media?parent=195"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tonala.gob.mx\/portal\/wp-json\/wp\/v2\/categories?post=195"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tonala.gob.mx\/portal\/wp-json\/wp\/v2\/tags?post=195"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}